{"id":980,"date":"2025-09-22T12:11:52","date_gmt":"2025-09-22T12:11:52","guid":{"rendered":"https:\/\/instaframer.com\/dinaspu\/?page_id=980"},"modified":"2025-11-17T04:26:34","modified_gmt":"2025-11-17T04:26:34","slug":"kawasan-permukiman","status":"publish","type":"page","link":"https:\/\/instaframer.com\/dinaspu\/kawasan-permukiman\/","title":{"rendered":"Bidang Kawasan Permukiman"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-fdff1306 alignfull uagb-is-root-container\"><div class=\"uagb-container__shape uagb-container__shape-bottom uagb-container__invert\" data-negative=\"false\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 937.5 120\" preserveAspectRatio=\"none\"><path class=\"uagb-container__shape-fill\" d=\"M937,129.8V-0.1H0v129.9C0,62.6,209.6,8.2,468.4,8.2S936.9,62.6,937,129.8z\"><\/path><\/svg><\/div><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-2ea1cf1b\">\n<div class=\"wp-block-uagb-container uagb-block-c65b938f\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-99f1bb67\"><div class=\"uagb-heading-text\">BIDANG<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-bf9c0f05 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Kawasan Permukiman<\/h1><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fe8ae009 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-5b47e45b\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ec26736e\"><p class=\"uagb-desc-text\">Melaksanakan sebagian tugas Kepala Dinas dalam perumusan kebijakan teknis, pengoordinasian, pembinaan, pengawasan, pengendalian, pengelolaan, fasilitasi, evaluasi, dan pelaporan kegiatan di bidang kawasan permukiman<\/p><\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-a94f99bd     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-3 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1418' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Anton-747x1024.jpeg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Anton-747x1024.jpeg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Anton-219x300.jpeg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tAnton\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1419' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Mutiara-747x1024.jpeg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Mutiara-747x1024.jpeg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Mutiara-219x300.jpeg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tRina\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1420' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Rina-747x1024.jpeg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Rina-747x1024.jpeg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/10\/Rina-219x300.jpeg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption spectra-image-gallery__media-thumbnail-caption--overlay\">\n\t\t\t\t\tMutiara\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\n<div class=\"wp-block-uagb-container uagb-block-4302794c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-dbcbb2a6\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f674db22\"><h2 class=\"uagb-heading-text\">Seksi<\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f35f5c8a\">\n<div class=\"wp-block-uagb-container uagb-block-4782d039\">\n<div class=\"wp-block-uagb-info-box uagb-block-a440c689 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M352 96C352 110.3 348.9 123.9 343.2 136.2L396 227.4C372.3 252.7 341.9 271.5 307.6 281L256 192H255.1L187.9 309.5C209.4 316.3 232.3 320 256 320C326.7 320 389.8 287.3 430.9 235.1C441.9 222.2 462.1 219.1 475.9 231C489.7 242.1 491.9 262.2 480.8 276C428.1 341.8 346.1 384 256 384C220.6 384 186.6 377.6 155.3 365.9L98.65 463.7C93.95 471.8 86.97 478.4 78.58 482.6L23.16 510.3C18.2 512.8 12.31 512.5 7.588 509.6C2.871 506.7 0 501.5 0 496V440.6C0 432.2 2.228 423.9 6.46 416.5L66.49 312.9C53.66 301.6 41.84 289.3 31.18 276C20.13 262.2 22.34 242.1 36.13 231C49.92 219.1 70.06 222.2 81.12 235.1C86.79 243.1 92.87 249.8 99.34 256.1L168.8 136.2C163.1 123.9 160 110.3 160 96C160 42.98 202.1 0 256 0C309 0 352 42.98 352 96L352 96zM256 128C273.7 128 288 113.7 288 96C288 78.33 273.7 64 256 64C238.3 64 224 78.33 224 96C224 113.7 238.3 128 256 128zM372.1 393.9C405.5 381.1 435.5 363.2 461.8 341L505.5 416.5C509.8 423.9 512 432.2 512 440.6V496C512 501.5 509.1 506.7 504.4 509.6C499.7 512.5 493.8 512.8 488.8 510.3L433.4 482.6C425 478.4 418.1 471.8 413.3 463.7L372.1 393.9z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\"><br><strong>Pendataan, Perencanaan dan Evaluasi Kawasan Permukiman<\/strong><\/h6><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d5ea53b7\">\n<div class=\"wp-block-uagb-info-box uagb-block-35dcb393 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M384 128h-128V0L384 128zM256 160H384v304c0 26.51-21.49 48-48 48h-288C21.49 512 0 490.5 0 464v-416C0 21.49 21.49 0 48 0H224l.0039 128C224 145.7 238.3 160 256 160zM64 88C64 92.38 67.63 96 72 96h80C156.4 96 160 92.38 160 88v-16C160 67.63 156.4 64 152 64h-80C67.63 64 64 67.63 64 72V88zM72 160h80C156.4 160 160 156.4 160 152v-16C160 131.6 156.4 128 152 128h-80C67.63 128 64 131.6 64 136v16C64 156.4 67.63 160 72 160zM197.5 316.8L191.1 315.2C168.3 308.2 168.8 304.1 169.6 300.5c1.375-7.812 16.59-9.719 30.27-7.625c5.594 .8438 11.73 2.812 17.59 4.844c10.39 3.594 21.83-1.938 25.45-12.34c3.625-10.44-1.891-21.84-12.33-25.47c-7.219-2.484-13.11-4.078-18.56-5.273V248c0-11.03-8.953-20-20-20s-20 8.969-20 20v5.992C149.6 258.8 133.8 272.8 130.2 293.7c-7.406 42.84 33.19 54.75 50.52 59.84l5.812 1.688c29.28 8.375 28.8 11.19 27.92 16.28c-1.375 7.812-16.59 9.75-30.31 7.625c-6.938-1.031-15.81-4.219-23.66-7.031l-4.469-1.625c-10.41-3.594-21.83 1.812-25.52 12.22c-3.672 10.41 1.781 21.84 12.2 25.53l4.266 1.5c7.758 2.789 16.38 5.59 25.06 7.512V424c0 11.03 8.953 20 20 20s20-8.969 20-20v-6.254c22.36-4.793 38.21-18.53 41.83-39.43C261.3 335 219.8 323.1 197.5 316.8z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\"><br><strong><br><strong>Pencegahan, Peningkatan Kualitas, dan Pemanfaatan Permukiman<\/strong><\/strong><\/h6><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-08d6061a\"><h2 class=\"uagb-heading-text\">Tugas &amp; Fungsi<\/h2><\/div>\n\n\n\n<ol class=\"wp-block-list\">\n<li>menyusun rencana dan program kegiatan Bidang Kawasan Permukiman berdasarkan peraturan perundang-undangan dan hasil evaluasi kegiatan tahun sebelumnya sebagai pedoman pelaksanaan tugas;&nbsp;<\/li>\n\n\n\n<li>menjabarkan perintah pimpinan melalui pengkajian permasalahan dan peraturan perundang-undangan agar pelaksanaan tugas berjalan efektif dan efisien;&nbsp;<\/li>\n\n\n\n<li>membagi tugas bawahan sesuai dengan jabatan dan kompetensinya serta memberikan arahan baik secara lisan maupun tertulis guna kelancaran pelaksanaan tugas;&nbsp;<\/li>\n\n\n\n<li>melaksanakan koordinasi dan konsultasi dengan instansi terkait baik vertikal maupun horizontal untuk mendapatkan informasi, masukan, serta 18 dalam rangka sinkronisasi dan harmonisasi pelaksanaan tugas;&nbsp;<\/li>\n\n\n\n<li>menelaah dan mengkaji peraturan perundang undangan sesuai lingkup tugasnya sebagai bahan atau pedoman untuk melaksanakan kegiatan;&nbsp;<\/li>\n\n\n\n<li>menyiapkan konsep kebijakan Kepala Dinas dan naskah dinas yang berkaitan dengan kegiatan di bidang kawasan permukiman;&nbsp;<\/li>\n\n\n\n<li>menyelenggarakan dan mengkoordinasikan pembinaan teknis kegiatan di bidang kawasan permukiman;&nbsp;<\/li>\n\n\n\n<li>h. menyelenggarakan pendataan, perencanaan, pencegahan dan peningkatan kawasan permukiman;&nbsp;<\/li>\n\n\n\n<li>menyelenggarakan pemanfaatan dan pengendalian kawasan permukiman sesuai peraturan perundang undangan;&nbsp;<\/li>\n\n\n\n<li>mengkoordinasikan penyiapan bahan perumusan kebijakan, analisis teknis, dan penyusunan rencana penyediaan Prasarana, Sarana dan Utilitas (PSU) kawasan permukiman;&nbsp;<\/li>\n\n\n\n<li>mengkoordinasikan penyiapan bahan pelaksanaan pemantauan dan evaluasi di bidang penyediaan Prasarana, Sarana dan Utilitas (PSU) kawasan permukiman kecuali pengelolaan dan pengembangan Sistem Pengelolaan Air Minum (SPAM), drainase, sanitasi dan resapan air limpahan skala Daerah;<\/li>\n\n\n\n<li>merencanakan dan mengkoordinasikan penerapan pencapaian indikator Standar Pelayanan Minimal (SPM) sesuai dengan bidang tugasnya dan peraturan perundang-undangan;&nbsp;<\/li>\n\n\n\n<li>melaksanakan pemantauan dan evaluasi pelaksanaan kegiatan Bidang Kawasan Permukiman dengan cara mengukur pencapaian program kerja yang telah disusun untuk bahan laporan dan kebijakan tindak lanjut;&nbsp;<\/li>\n\n\n\n<li>mengevaluasi dan menilai prestasi kerja bawahan berdasarkan sasaran kerja pegawai dan perilaku kerja sesuai ketentuan dalam rangka peningkatan karir, pemberian penghargaan dan sanksi;&nbsp;<\/li>\n\n\n\n<li>menyusun laporan pelaksanaan kegiatan kepada pimpinan sebagai wujud akuntabilitas dan transparansi pelaksanaan kegiatan;&nbsp;<\/li>\n\n\n\n<li>menyampaikan saran dan pertimbangan kepada pimpinan baik lisan maupun tertulis berdasarkan kajian agar kegiatan berjalan lancar serta untuk menghindari penyimpangan; dan&nbsp;<\/li>\n\n\n\n<li>melaksanakan tugas kedinasan lain dari pimpinan sesuai dengan tugas dan fungsi unit kerjanya<\/li>\n<\/ol>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>BIDANG Melaksanakan sebagian tugas Kepala Dinas dalam perumusan kebijakan teknis, pengoordinasian, pembinaan, pengawasan, pengendalian, pengelolaan, fasilitasi, evaluasi, dan pelaporan kegiatan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-980","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"spectra_custom_meta":{"site-sidebar-layout":["no-sidebar"],"ast-site-content-layout":["full-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"site-post-title":["disabled"],"theme-transparent-header-meta":["enabled"],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"astra-main-page-id":["110806"],"ast_self_id_110806":["1"],"_wxr_import_user_slug":["devanshus"],"_astra_sites_imported_post":["1"],"_astra_sites_enable_for_batch":["1"],"_edit_lock":["1764840907:1"],"_edit_last":["1"],"_ahcfree_total_views":["3"],"_ahcfree_unique_visitors":["3"],"_uag_css_file_name":["uag-css-980.css"],"_uag_js_file_name":["uag-js-980.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:191980:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-slide .spectra-image-gallery__media-wrapper{display:block !important}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow .25s;-moz-transition:box-shadow .25s;-o-transition:box-shadow .25s;transition:box-shadow .25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter .5s,transform .5s;-moz-transition:filter .5s,transform .5s;-o-transition:filter .5s,transform .5s;transition:filter .5s,transform .5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow .25s,-webkit-backdrop-filter .5s;-moz-transition:box-shadow .25s,backdrop-filter .5s;-o-transition:box-shadow .25s,backdrop-filter .5s;transition:box-shadow .25s,backdrop-filter .5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color .25s;-moz-transition:background-color .25s;-o-transition:background-color .25s;transition:background-color .25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:rgba(0,0,0,0);padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-arrows:disabled{opacity:.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:rgba(0,0,0,0);border:0;outline:none;background:rgba(0,0,0,0);-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-button.disabled{opacity:.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:.5em;background-color:rgba(0,0,0,0);border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0, 0, 0, 0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:.5;transform:scale(75%);-webkit-transition-property:opacity,transform;-moz-transition-property:opacity,transform;-o-transition-property:opacity,transform;transition-property:opacity,transform;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:rgba(0,0,0,0);border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:rgba(0,0,0,0);transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media(max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media(max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape-bottom svg{height: 106px;width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: var(--ast-global-color-4);}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__video-wrap video{opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdff1306{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdff1306 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fdff1306{box-shadow: 0px 0px   #00000070 ;padding-top: 200px;padding-bottom: 200px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/Blog-2.png);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fdff1306::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-2);opacity: 0.8;}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ea1cf1b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ea1cf1b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2ea1cf1b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c65b938f{max-width: 7%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c65b938f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c65b938f{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 2px;padding-bottom: 2px;padding-left: 1px;padding-right: 1px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 99px;border-top-right-radius: 99px;border-bottom-left-radius: 99px;border-bottom-right-radius: 99px;border-color: inherit;background-color: rgba(255,255,255,0.14);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-bf9c0f05 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-bf9c0f05 .uagb-ifb-icon svg{fill: #333;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 10px;margin-top: 0px;margin-left: 170px;margin-right: 170px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 240px;margin-right: 240px;}.uagb-block-bf9c0f05 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-bf9c0f05 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-bf9c0f05 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-bf9c0f05 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf9c0f05 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-bf9c0f05.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe8ae009{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe8ae009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 80px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fe8ae009{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(u002du002dast-global-color-5);;row-gap: 80px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b47e45b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b47e45b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 8px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5b47e45b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 8px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 140px;padding-bottom: 72px;padding-left: 140px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e .uagb-heading-text{margin-bottom: 15px;}.uagb-block-a94f99bd.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-a94f99bd .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-a94f99bd .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-a94f99bd .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-a94f99bd .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-a94f99bd .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-a94f99bd .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-a94f99bd .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-a94f99bd .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__media{border-top-left-radius: 12px;border-top-right-radius: 12px;border-bottom-left-radius: 12px;border-bottom-right-radius: 12px;box-shadow: 0px 0px   ;}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bdspectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-a94f99bd .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-a94f99bd .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-4302794c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4302794c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4302794c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4302794c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4302794c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4302794c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4302794c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 80px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4302794c{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 80px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dbcbb2a6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dbcbb2a6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dbcbb2a6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dbcbb2a6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dbcbb2a6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dbcbb2a6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dbcbb2a6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 8px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-dbcbb2a6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 8px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 140px;padding-bottom: 0px;padding-left: 140px;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f35f5c8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f35f5c8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f35f5c8a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4782d039{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4782d039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4782d039{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-a440c689 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-a440c689.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-a440c689.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 8px;margin-left: 0px;margin-right: 0px;}.uagb-block-a440c689 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-a440c689 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-a440c689 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-a440c689 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a440c689.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-a440c689 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-7);border-radius: 50%;}.uagb-block-a440c689 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-7);}.uagb-block-a440c689 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-a440c689 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-a440c689.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-a440c689.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a440c689 .uagb-iconbox-icon-wrap{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-a440c689.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5ea53b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d5ea53b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d5ea53b7{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-35dcb393 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-35dcb393.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-35dcb393.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 8px;margin-left: 0px;margin-right: 0px;}.uagb-block-35dcb393 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-35dcb393 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-35dcb393 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-35dcb393 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-35dcb393.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-7);border-radius: 50%;}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-7);}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-35dcb393 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-35dcb393.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-35dcb393.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-35dcb393 .uagb-iconbox-icon-wrap{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading {text-align: center;padding-top: 32px;padding-right: 140px;padding-bottom: 24px;padding-left: 140px;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdff1306{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdff1306 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fdff1306{padding-top: 120px;padding-bottom: 120px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/Blog-2.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-fdff1306::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-2);opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ea1cf1b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ea1cf1b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2ea1cf1b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c65b938f{max-width: 12%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c65b938f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c65b938f{padding-top: 2px;padding-bottom: 2px;padding-left: 1px;padding-right: 1px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: rgba(255,255,255,0.14);;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 60px;margin-right: 60px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 180px;margin-right: 180px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf9c0f05 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe8ae009{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe8ae009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;}.wp-block-uagb-container.uagb-block-fe8ae009{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(u002du002dast-global-color-5);;row-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b47e45b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b47e45b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5b47e45b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 80px;padding-bottom: 0px;padding-left: 80px;}.uagb-block-a94f99bd.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-a94f99bd .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-a94f99bd .spectra-image-gallery__control-button{padding:    ;}.uagb-block-a94f99bd .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4302794c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4302794c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;}.wp-block-uagb-container.uagb-block-4302794c{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;row-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dbcbb2a6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dbcbb2a6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dbcbb2a6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 80px;padding-bottom: 0px;padding-left: 80px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f35f5c8a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f35f5c8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f35f5c8a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4782d039{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4782d039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4782d039{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 24px;font-size: 24px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a440c689 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-iconbox-icon-wrap{width: 24px;height: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-a440c689.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5ea53b7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d5ea53b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d5ea53b7{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 24px;font-size: 24px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-35dcb393 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap{width: 24px;height: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-35dcb393.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 80px;padding-bottom: 0px;padding-left: 80px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdff1306{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdff1306 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fdff1306{padding-top: 120px;padding-bottom: 120px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/Blog-2.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-fdff1306::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-2);opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ea1cf1b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ea1cf1b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2ea1cf1b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c65b938f{max-width: 80px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c65b938f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c65b938f{padding-top: 2px;padding-bottom: 2px;padding-left: 1px;padding-right: 1px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: rgba(255,255,255,0.14);;flex-wrap: wrap;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf9c0f05 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe8ae009{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe8ae009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fe8ae009{padding-top: 60px;padding-bottom: 60px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(u002du002dast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b47e45b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b47e45b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5b47e45b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e .uagb-heading-text{margin-bottom: 8px;}.uagb-block-a94f99bd.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-a94f99bd .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-a94f99bd .spectra-image-gallery__control-button{padding:    ;}.uagb-block-a94f99bd .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-a94f99bd .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-a94f99bd .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-a94f99bd+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4302794c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4302794c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4302794c{padding-top: 60px;padding-bottom: 60px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dbcbb2a6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dbcbb2a6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dbcbb2a6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-f674db22.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f35f5c8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f35f5c8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f35f5c8a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4782d039{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4782d039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4782d039{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;flex-wrap: wrap;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 24px;font-size: 24px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a440c689 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-iconbox-icon-wrap{width: 24px;height: 24px;line-height: 24px;}.uagb-block-a440c689.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5ea53b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d5ea53b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d5ea53b7{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;flex-wrap: wrap;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 24px;font-size: 24px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-35dcb393 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap{width: 24px;height: 24px;line-height: 24px;}.uagb-block-35dcb393.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-08d6061a.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e5f40570{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e5f40570 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 44px;}.wp-block-uagb-container.uagb-block-e5f40570{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 60px;padding-right: 60px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: var(--ast-global-color-0);;row-gap: 20px;column-gap: 44px;}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7e1a1ce{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7e1a1ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c7e1a1ce{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 100px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34a517cb{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34a517cb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-34a517cb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-75a92e01 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-75a92e01 .uagb-ifb-icon svg{fill: #333;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-75a92e01.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-75a92e01.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 16px;}.uagb-block-75a92e01 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-75a92e01 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-75a92e01 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-75a92e01 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75a92e01 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-75a92e01.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75a92e01.wp-block-uagb-info-box .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{color: var(--ast-global-color-0);background-color: var(--ast-global-color-7);}.uagb-block-75a92e01.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{color: var(--ast-global-color-0);background-color: var(--ast-global-color-7);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: #333;border-style: none;}.uagb-block-75a92e01 .uagb-ifb-button-wrapper .uagb-infobox-cta-link svg{fill: var(--ast-global-color-0);}.uagb-block-75a92e01 .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: #333;border-style: none;}[dir=rtl] .uagb-block-75a92e01 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e5f40570{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e5f40570 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e5f40570{padding-top: 40px;padding-bottom: 40px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-0);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7e1a1ce{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7e1a1ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c7e1a1ce{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34a517cb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34a517cb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-34a517cb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75a92e01 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75a92e01 .uagb-infobox-cta-link{border-style: none;border-color: #333;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e5f40570{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e5f40570 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e5f40570{padding-top: 32px;padding-bottom: 32px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-0);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7e1a1ce{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7e1a1ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c7e1a1ce{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34a517cb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34a517cb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-34a517cb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75a92e01 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75a92e01 .uagb-infobox-cta-link{border-style: none;border-color: #333;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-211a6307{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-211a6307 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-211a6307{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-73fe9699.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-73fe9699 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-73fe9699.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: 107px;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-211a6307{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-211a6307 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-211a6307{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-211a6307{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-211a6307 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-211a6307{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-07791abd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-07791abd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-07791abd{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-07791abd{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-07791abd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-07791abd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-07791abd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-07791abd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-07791abd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-heading-text{color: #fefefe;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-icon svg{width:30px}.uagb-icon-wrapper .uagb-svg-wrapper{transition:box-shadow .2s ease}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdbc477e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdbc477e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fdbc477e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-915a0751{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-915a0751 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-915a0751{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;} .uagb-block-d54b4f1a.uagb-icon-wrapper{text-align: left;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-d54b4f1a.uagb-icon-wrapper svg{width: 12px;height: 12px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-7);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;background: var(--ast-global-color-0);padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;box-shadow: 0px 0px 0 #00000070 ;border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab3b6093{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab3b6093 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ab3b6093{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-98bbd9c1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-98bbd9c1 .uagb-ifb-icon svg{fill: #333;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-98bbd9c1.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 2px;}.uagb-block-98bbd9c1.wp-block-uagb-info-box .uagb-ifb-desc{color: rgba(255,255,255,0.74);margin-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-98bbd9c1 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-98bbd9c1 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-98bbd9c1 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-98bbd9c1.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-98bbd9c1 .uagb-ifb-title{font-weight: 900;font-size: 16px;}[dir=rtl] .uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdbc477e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdbc477e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fdbc477e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-915a0751{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-915a0751 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-915a0751{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab3b6093{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab3b6093 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ab3b6093{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-98bbd9c1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdbc477e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdbc477e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fdbc477e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-915a0751{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-915a0751 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-915a0751{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab3b6093{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab3b6093 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ab3b6093{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-98bbd9c1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c212dd68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c212dd68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c212dd68{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-797ec235{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-797ec235 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-797ec235{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;} .uagb-block-4d869d83.uagb-icon-wrapper{text-align: left;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-4d869d83.uagb-icon-wrapper svg{width: 12px;height: 12px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-7);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;background: var(--ast-global-color-0);padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;box-shadow: 0px 0px 0 #00000070 ;border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af66883b{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af66883b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-af66883b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-e7e7f750 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e7e7f750 .uagb-ifb-icon svg{fill: #333;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e7e7f750.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 2px;}.uagb-block-e7e7f750.wp-block-uagb-info-box .uagb-ifb-desc{color: rgba(255,255,255,0.74);margin-bottom: 0px;}.uagb-block-e7e7f750 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e7e7f750 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e7e7f750 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e7e7f750 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e7e7f750 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-e7e7f750.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e7e7f750 .uagb-ifb-title{font-weight: 900;font-size: 16px;}[dir=rtl] .uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c212dd68{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c212dd68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c212dd68{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-797ec235{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-797ec235 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-797ec235{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af66883b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af66883b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-af66883b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e7e7f750 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c212dd68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c212dd68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c212dd68{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-797ec235{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-797ec235 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-797ec235{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af66883b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af66883b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-af66883b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e7e7f750 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4ed6bcbf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4ed6bcbf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4ed6bcbf{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb563004{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb563004 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eb563004{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;} .uagb-block-f286b3bf.uagb-icon-wrapper{text-align: left;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-f286b3bf.uagb-icon-wrapper svg{width: 12px;height: 12px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-7);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;background: var(--ast-global-color-0);padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;box-shadow: 0px 0px 0 #00000070 ;border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d1acc551{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d1acc551 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d1acc551{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-1d6b19b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-1d6b19b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-1d6b19b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 2px;}.uagb-block-1d6b19b8.wp-block-uagb-info-box .uagb-ifb-desc{color: rgba(255,255,255,0.74);margin-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-1d6b19b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-1d6b19b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d6b19b8 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-1d6b19b8.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-1d6b19b8 .uagb-ifb-title{font-weight: 900;font-size: 16px;}[dir=rtl] .uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4ed6bcbf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4ed6bcbf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4ed6bcbf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb563004{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb563004 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eb563004{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d1acc551{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d1acc551 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d1acc551{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d6b19b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4ed6bcbf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4ed6bcbf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4ed6bcbf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb563004{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb563004 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eb563004{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d1acc551{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d1acc551 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d1acc551{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d6b19b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}\";s:2:\"js\";s:1601:\"document.addEventListener(\"DOMContentLoaded\", function(){ \t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-d54b4f1a' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-4d869d83' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-f286b3bf' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\t });\";s:18:\"current_block_list\";a:16:{i:0;s:14:\"uagb\/container\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:13:\"uagb\/info-box\";i:5;s:18:\"uagb\/image-gallery\";i:6;s:9:\"core\/list\";i:7;s:14:\"core\/list-item\";i:8;s:11:\"core\/search\";i:9;s:10:\"core\/group\";i:10;s:12:\"core\/heading\";i:11;s:17:\"core\/latest-posts\";i:12;s:20:\"core\/latest-comments\";i:13;s:13:\"core\/archives\";i:14;s:15:\"core\/categories\";i:18;s:14:\"core\/paragraph\";i:20;s:10:\"uagb\/image\";i:23;s:9:\"uagb\/icon\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1777463479\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"code.magna","author_link":"https:\/\/instaframer.com\/dinaspu\/author\/code-magna\/"},"uagb_comment_info":0,"uagb_excerpt":"BIDANG Melaksanakan sebagian tugas Kepala Dinas dalam perumusan kebijakan teknis, pengoordinasian, pembinaan, pengawasan, pengendalian, pengelolaan, fasilitasi, evaluasi, dan pelaporan kegiatan [&hellip;]","meta_box":[],"_links":{"self":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages\/980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/comments?post=980"}],"version-history":[{"count":7,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages\/980\/revisions"}],"predecessor-version":[{"id":1616,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages\/980\/revisions\/1616"}],"wp:attachment":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/media?parent=980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}