{"id":14,"date":"2025-09-17T05:49:54","date_gmt":"2025-09-17T05:49:54","guid":{"rendered":"https:\/\/instaframer.com\/dinaspu\/contact\/"},"modified":"2025-09-25T13:29:00","modified_gmt":"2025-09-25T13:29:00","slug":"kontak","status":"publish","type":"page","link":"https:\/\/instaframer.com\/dinaspu\/kontak\/","title":{"rendered":"Kontak"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-fdff1306 alignfull uagb-is-root-container\"><div class=\"uagb-container__shape uagb-container__shape-bottom uagb-container__invert\" data-negative=\"false\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 937.5 120\" preserveAspectRatio=\"none\"><path class=\"uagb-container__shape-fill\" d=\"M937,129.8V-0.1H0v129.9C0,62.6,209.6,8.2,468.4,8.2S936.9,62.6,937,129.8z\"><\/path><\/svg><\/div><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-2ea1cf1b\">\n<div class=\"wp-block-uagb-container uagb-block-c65b938f\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-99f1bb67\"><div class=\"uagb-heading-text\">Kontak<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-bf9c0f05 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Hubungi Kami<\/h1><\/div><p class=\"uagb-ifb-desc\">Jangan ragu hubungi Disperkim Kendal untuk informasi layanan, kegiatan, dan program terbaru.<\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-cacb9c7b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-4cdcc25f\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-27ca6c40\"><div class=\"uagb-heading-text\">Kami Siap Membantu<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-1d2e6ada uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Mari Saling Terhubung dengan Kami!<\/h2><\/div><p class=\"uagb-ifb-desc\">Formulir ini tersedia untuk memudahkan Anda menyampaikan pertanyaan, masukan atau permintaan informasi.<br>Anda juga dapat menghubungi kami lewat telepon, email, atau datang langsung ke kantor Disperkim Kendal.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9a4f633f\">\n<div class=\"wp-block-uagb-info-box uagb-block-93a311ce uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\"><strong>Senin-Kamis<\/strong><\/p><\/div><p class=\"uagb-ifb-desc\">07.00-15.30 WIB<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-6ec30441 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\"><strong>Jum&#8217;at<\/strong><\/p><\/div><p class=\"uagb-ifb-desc\">07.00-10.30 WIB<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-622f196b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\"><strong>Sabtu &amp; Minggu<\/strong><\/p><\/div><p class=\"uagb-ifb-desc\">Tutup\/Libur<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uag-hide-mob uagb-layout-flex uagb-block-f35f5c8a\">\n<div class=\"wp-block-uagb-container uagb-block-4960d791\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-1c697a61 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/google.svg ,https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/google.svg 780w, https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/google.svg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/google.svg\" alt=\"\" class=\"uag-image-328\" width=\"60\" height=\"60\" title=\"google\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-star-rating uagb-block-ff661e74\"><p class=\"uag-star-rating__title\">260+ reviews (4.95 of 5)<\/p><div class=\"uag-star-rating\" title=\"4.9\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c2bb3c7e\">\t\t\t<div class=\"srfm-form-container srfm-form-container-334 srfm-bg-color\">\n\t\t\t<style>\n\t\t\t\t\/* Need to check and remove the input variables related to the Style Tab. *\/\n\t\t\t\t.srfm-form-container-334 {\n\t\t\t\t\t\/* New test variables *\/\n\t\t\t\t\t--srfm-color-scheme-primary: var(--ast-global-color-0);\n\t\t\t\t\t--srfm-color-scheme-text-on-primary: var(--ast-global-color-2);\n\t\t\t\t\t--srfm-color-scheme-text: var(--ast-global-color-2);\n\t\t\t\t\t--srfm-quill-editor-color: var(--ast-global-color-0);\n\n\t\t\t\t\t--srfm-color-input-label: var(--ast-global-color-2);\n\t\t\t\t\t--srfm-color-input-description: hsl( from var(--ast-global-color-2) h s l \/ 0.65 );\n\t\t\t\t\t--srfm-color-input-placeholder: hsl( from var(--ast-global-color-2) h s l \/ 0.5 );\n\t\t\t\t\t--srfm-color-input-text: var(--ast-global-color-2);\n\t\t\t\t\t--srfm-color-input-prefix: hsl( from var(--ast-global-color-2) h s l \/ 0.65 );\n\t\t\t\t\t--srfm-color-input-background: hsl( from var(--ast-global-color-2) h s l \/ 0.02 );\n\t\t\t\t\t--srfm-color-input-background-hover: hsl( from var(--ast-global-color-2) h s l \/ 0.05 );\n\t\t\t\t\t--srfm-color-input-background-disabled: hsl( from var(--ast-global-color-2) h s l \/ 0.07 );\n\t\t\t\t\t--srfm-color-input-border: hsl( from var(--ast-global-color-2) h s l \/ 0.25 );\n\t\t\t\t\t--srfm-color-input-border-disabled: hsl( from var(--ast-global-color-2) h s l \/ 0.15 );\n\t\t\t\t\t--srfm-color-multi-choice-svg: hsl( from var(--ast-global-color-2) h s l \/ 0.7 );\n\t\t\t\t\t--srfm-color-input-border-hover: hsl( from var(--ast-global-color-0) h s l \/ 0.65 );\n\t\t\t\t\t--srfm-color-input-border-focus-glow: hsl( from var(--ast-global-color-0) h s l \/ 0.15 );\n\t\t\t\t\t--srfm-color-input-selected: hsl( from var(--ast-global-color-0) h s l \/ 0.1 );\n\t\t\t\t\t--srfm-btn-color-hover: hsl( from var(--ast-global-color-0) h s l \/ 0.9 );\n\t\t\t\t\t--srfm-btn-color-disabled: hsl( from var(--ast-global-color-0) h s l \/ 0.25 );\n\n\t\t\t\t\t\/* Dropdown Variables *\/\n\t\t\t\t\t--srfm-dropdown-input-background-hover: hsl( from var(--ast-global-color-2) h s l \/ 0.05 );\n\t\t\t\t\t--srfm-dropdown-option-background-hover: hsl( from var(--ast-global-color-2) h s l \/ 0.10 );\n\t\t\t\t\t--srfm-dropdown-option-background-selected: hsl( from var(--ast-global-color-2) h s l \/ 0.05 );\n\t\t\t\t\t--srfm-dropdown-option-selected-icon: hsl( from var(--ast-global-color-2) h s l \/ 0.65 );\n\t\t\t\t\t--srfm-dropdown-option-text-color: hsl( from var(--ast-global-color-2) h s l \/ 0.80 );\n\t\t\t\t\t--srfm-dropdown-option-selected-text: var(--ast-global-color-2);\n\t\t\t\t\t--srfm-dropdown-badge-background: hsl( from var(--ast-global-color-2) h s l \/ 0.05 );\n\t\t\t\t\t--srfm-dropdown-badge-background-hover: hsl( from var(--ast-global-color-2) h s l \/ 0.10 );\n\t\t\t\t\t--srfm-dropdown-menu-border-color: hsl( from var(--ast-global-color-2) h s l \/ 0.10 );\n\t\t\t\t\t--srfm-dropdown-placeholder-color: hsl( from var(--ast-global-color-2) h s l \/ 0.50 );\n\t\t\t\t\t--srfm-dropdown-icon-color: hsl( from var(--ast-global-color-2) h s l \/ 0.65 );\n\t\t\t\t\t--srfm-dropdown-icon-disabled: hsl( from var(--ast-global-color-2) h s l \/ 0.25 );\n\n\t\t\t\t\t\/* Background Control Variables *\/\n\t\t\t\t\t--srfm-instant-form-padding-top: 32px;--srfm-instant-form-padding-right: 32px;--srfm-instant-form-padding-bottom: 32px;--srfm-instant-form-padding-left: 32px;--srfm-instant-form-border-radius-top: 12px;--srfm-instant-form-border-radius-right: 12px;--srfm-instant-form-border-radius-bottom: 12px;--srfm-instant-form-border-radius-left: 12px;--srfm-form-padding-top: 0px;--srfm-form-padding-right: 0px;--srfm-form-padding-bottom: 0px;--srfm-form-padding-left: 0px;--srfm-form-border-radius-top: 0px;--srfm-form-border-radius-right: 0px;--srfm-form-border-radius-bottom: 0px;--srfm-form-border-radius-left: 0px;--srfm-bg-color: #ffffff;--srfm-bg-overlay-opacity: 1;\t\t\t\t\t--srfm-row-gap-between-blocks: 18px;--srfm-address-label-font-size: 16px;--srfm-address-label-line-height: 24px;--srfm-address-description-font-size: 14px;--srfm-address-description-line-height: 20px;--srfm-col-gap-between-fields: 16px;--srfm-row-gap-between-fields: 16px;--srfm-gap-below-address-label: 14px;--srfm-dropdown-font-size: 14px;--srfm-dropdown-gap-between-input-menu: 4px;--srfm-dropdown-badge-padding: 2px 6px;--srfm-dropdown-multiselect-font-size: 12px;--srfm-dropdown-multiselect-line-height: 16px;--srfm-dropdown-padding-right: 12px;--srfm-dropdown-padding-right-icon: calc( var( --srfm-dropdown-padding-right ) + 20px );--srfm-dropdown-multiselect-padding: 8px var( --srfm-dropdown-padding-right-icon ) 8px 8px;--srfm-input-height: 44px;--srfm-input-field-padding: 10px 12px;--srfm-input-field-font-size: 16px;--srfm-input-field-line-height: 24px;--srfm-input-field-margin-top: 6px;--srfm-input-field-margin-bottom: 6px;--srfm-checkbox-label-font-size: 16px;--srfm-checkbox-label-line-height: 24px;--srfm-checkbox-description-font-size: 14px;--srfm-checkbox-description-line-height: 20px;--srfm-check-ctn-width: 16px;--srfm-check-ctn-height: 16px;--srfm-check-svg-size: 10px;--srfm-checkbox-margin-top-frontend: 4px;--srfm-checkbox-margin-top-editor: 6px;--srfm-check-gap: 8px;--srfm-checkbox-description-margin-left: 24px;--srfm-flag-section-padding: 10px 0 10px 12px;--srfm-gap-between-icon-text: 8px;--srfm-label-font-size: 16px;--srfm-label-line-height: 24px;--srfm-description-font-size: 14px;--srfm-description-line-height: 20px;--srfm-btn-padding: 10px 14px;--srfm-btn-font-size: 16px;--srfm-btn-line-height: 24px;--srfm-multi-choice-horizontal-padding: 20px;--srfm-multi-choice-vertical-padding: 20px;--srfm-multi-choice-internal-option-gap: 8px;--srfm-multi-choice-vertical-svg-size: 40px;--srfm-multi-choice-horizontal-image-size: 24px;--srfm-multi-choice-vertical-image-size: 120px;--srfm-multi-choice-outer-padding: 2px;\t\t\t\t}\n\t\t\t<\/style>\n\t\t\t\t\t\t\t<form method=\"post\" enctype=\"multipart\/form-data\" id=\"srfm-form-334\" class=\"srfm-form \"\n\t\t\t\tform-id=\"334\" after-submission=\"hide form\" message-type=\"same page\" success-url=\"\" ajaxurl=\"https:\/\/instaframer.com\/dinaspu\/wp-admin\/admin-ajax.php\" data-submit-token=\"25d5d6dbbfa3e64d2e9c6edf2ce3ceb65a0dca65869a6312aa0127dfc727ca8d\"\n\t\t\t\t>\n\t\t\t\t\n\t\t\t\t<input type=\"hidden\" value=\"334\" name=\"form-id\">\n\t\t\t\t<input type=\"hidden\" value=\"\" name=\"srfm-sender-email-field\" id=\"srfm-sender-email\">\n\t\t\t\t<input type=\"hidden\" value=\"\" id=\"srfm-page-break\">\n\t\t\t\t\t\t<p id=\"srfm-error-message\" class=\"srfm-common-error-message srfm-error-message srfm-head-error\" hidden>\t\t<span class=\"srfm-icon\" aria-hidden=\"true\">\n\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='20' height='20' fill='none'><path d='M9.99935 18.3327C14.6017 18.3327 18.3327 14.6017 18.3327 9.99935C18.3327 5.39698 14.6017 1.66602 9.99935 1.66602C5.39698 1.66602 1.66602 5.39698 1.66602 9.99935C1.66602 14.6017 5.39698 18.3327 9.99935 18.3327Z' stroke='currentColor' stroke-width='1.5' stroke-linecap='round' stroke-linejoin='round' \/><path d='M10 6.66602V9.99935' stroke='currentColor' stroke-width='1.5' stroke-linecap='round' stroke-linejoin='round' \/><path d='M10 13.334H10.0083' stroke='currentColor' stroke-width='1.5' stroke-linecap='round' stroke-linejoin='round' \/><\/svg>\t\t<\/span>\n\t\t<span class=\"srfm-error-content\">There was an error trying to submit your form. Please try again.<\/span><\/p>\n\t\t\t\t\t<div data-block-id=\"f4e29664\" class=\"srfm-block-single srfm-block srfm-input-block srf-input-f4e29664-block  srfm-block-width-50 srfm-slug-first-name 334\" >\n\t\t\t\t\t\t\t\t<label id=\"srfm-label-f4e29664-lbl-TmFtYSBEZXBhbg\" for=\"srfm-input-f4e29664-lbl-TmFtYSBEZXBhbg\" class=\"srfm-block-label\">\n\t\t\t\t\t\tNama Depan\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"srfm-required\" aria-hidden=\"true\"> *<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-block-wrap\">\n\t\t\t\t<input class=\"srfm-input-common srfm-input-input\" type=\"text\" name=\"srfm-input-f4e29664-lbl-TmFtYSBEZXBhbg-first-name\" id=\"srfm-input-f4e29664-lbl-TmFtYSBEZXBhbg\"\n\t\t\t\t\taria-describedby='srfm-error-f4e29664'\t\t\t\t\tdata-required=\"true\" aria-required=\"true\" data-unique=\"false\" maxlength=\"100\" value=\"\"  data-srfm-mask=\"none\"   \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"srfm-error-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-error-message\" data-srfm-id=\"srfm-error-f4e29664\" data-error-msg=\"This field is required.\" data-unique-msg=\"Value needs to be unique.\">\n\t\t\t\t\t\tThis field is required.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\n\t\t\t<div data-block-id=\"036e674b\" class=\"srfm-block-single srfm-block srfm-input-block srf-input-036e674b-block  srfm-block-width-50 srfm-slug-last-name 334\" >\n\t\t\t\t\t\t\t\t<label id=\"srfm-label-036e674b-lbl-TmFtYSBCZWxha2FuZw\" for=\"srfm-input-036e674b-lbl-TmFtYSBCZWxha2FuZw\" class=\"srfm-block-label\">\n\t\t\t\t\t\tNama Belakang\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-block-wrap\">\n\t\t\t\t<input class=\"srfm-input-common srfm-input-input\" type=\"text\" name=\"srfm-input-036e674b-lbl-TmFtYSBCZWxha2FuZw-last-name\" id=\"srfm-input-036e674b-lbl-TmFtYSBCZWxha2FuZw\"\n\t\t\t\t\taria-describedby='srfm-error-036e674b'\t\t\t\t\tdata-required=\"false\" aria-required=\"false\" data-unique=\"false\" maxlength=\"100\" value=\"\"  data-srfm-mask=\"none\"   \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"srfm-error-wrap\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-error-message\" data-srfm-id=\"srfm-error-036e674b\" data-error-msg=\"This field is required.\" data-unique-msg=\"Value needs to be unique.\">\n\t\t\t\t\t\tThis field is required.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\n\t\t\t<div data-block-id=\"d18ed47c\" class=\"srfm-block-single srfm-block srfm-email-block srf-email-d18ed47c-block  srfm-block-width-50 srfm-slug-email 334 srfm-email-block-wrap\">\n\t\t\t\t<div class=\"srfm-email-block srf-email-d18ed47c-block\">\n\t\t\t\t\t\t\t\t\t\t<label id=\"srfm-label-d18ed47c-lbl-RW1haWw\" for=\"srfm-email-d18ed47c-lbl-RW1haWw\" class=\"srfm-block-label\">\n\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"srfm-required\" aria-hidden=\"true\"> *<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-block-wrap\">\n\t\t\t\t\t\t<input class=\"srfm-input-common srfm-input-email\" type=\"email\" name=\"srfm-email-d18ed47c-lbl-RW1haWw-email\" id=\"srfm-email-d18ed47c-lbl-RW1haWw\"\n\t\t\t\t\t\taria-describedby='srfm-error-d18ed47c'\t\t\t\t\t\tdata-required=\"true\" aria-required=\"true\" data-unique=\"false\" value=\"\"   \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"srfm-error-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-error-message\" data-srfm-id=\"srfm-error-d18ed47c\" data-error-msg=\"This field is required.\" data-unique-msg=\"Value needs to be unique.\">\n\t\t\t\t\t\tThis field is required.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\n\t\t<div data-block-id=\"e723ecf6\" class=\"srfm-block-single srfm-block srfm-phone-block srf-phone-e723ecf6-block srfm-block-width-50 334\">\n\t\t\t\t\t\t\t\t<label id=\"srfm-label-e723ecf6-lbl-VGVsZXBvbg\" for=\"srfm-phone-e723ecf6-lbl-VGVsZXBvbg\" class=\"srfm-block-label\">\n\t\t\t\t\t\tTelepon\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"srfm-required\" aria-hidden=\"true\"> *<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-block-wrap\">\n\t\t\t\t<input type=\"tel\"\n\t\t\t\t\tclass=\"srfm-input-common srfm-input-phone\"\n\t\t\t\t\tname=\"srfm-phone-e723ecf6-lbl-VGVsZXBvbg-phone-number\"\n\t\t\t\t\tid=\"srfm-phone-e723ecf6-lbl-VGVsZXBvbg\"\n\t\t\t\t\taria-describedby='srfm-error-e723ecf6'\t\t\t\t\tdata-required=\"true\"\n\t\t\t\t\taria-required=\"true\"\n\t\t\t\t\tdefault-country=\"us\"\n\t\t\t\t\t\t\t\t\t\tvalue=\"\"\n\t\t\t\t\t\t\t\t\t\tdata-unique=\"false\">\n\t\t\t<\/div>\n\t\t\t<div class=\"srfm-error-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"srfm-error-message\" data-srfm-id=\"srfm-error-e723ecf6\" data-error-msg=\"This field is required.\" data-unique-msg=\"Value needs to be unique.\">\n\t\t\t\t\t\tThis field is required.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\n\t\t<div data-block-id=\"83793496\" class=\"srfm-block-single srfm-block srfm-textarea-block srf-textarea-83793496-block  srfm-block-width-100 334\">\n\t\t\t\t\t\t\t\t<label id=\"srfm-label-83793496-lbl-UGVzYW4-1293\" for=\"srfm-textarea-83793496-lbl-UGVzYW4-1293\" class=\"srfm-block-label\">\n\t\t\t\t\t\tPesan\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"srfm-required\" aria-hidden=\"true\"> *<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"srfm-block-wrap\">\n\t\t\t\t<textarea\n\t\t\t\t\tclass=\"srfm-input-common srfm-input-textarea\"\n\t\t\t\t\tname=\"srfm-textarea-83793496-lbl-UGVzYW4-your-message\"\n\t\t\t\t\tid=\"srfm-textarea-83793496-lbl-UGVzYW4-1293\"\n\t\t\t\t\taria-describedby='srfm-error-83793496'\t\t\t\t\tdata-required=\"true\" aria-required=\"true\"  rows=\"4\"  \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t><\/textarea>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"srfm-error-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"srfm-error-message\" data-srfm-id=\"srfm-error-83793496\" data-error-msg=\"This field is required.\">\n\t\t\t\t\t\tThis field is required.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"srfm-submit-container \" style=\"\">\n\t\t\t\t\t\t<div style=\"width: ; text-align: left\" class=\"wp-block-button\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button style=\"\" id=\"srfm-submit-btn\" class=\"srfm-btn-frontend srfm-button srfm-submit-button\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t<div class=\"srfm-submit-wrap\">\n\t\t\t\t\t\t\t\t\tKirim\t\t\t\t\t\t\t\t<div class=\"srfm-loader\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p id=\"srfm-error-message\" class=\"srfm-common-error-message srfm-error-message srfm-footer-error\" hidden>\t\t<span class=\"srfm-icon\" aria-hidden=\"true\">\n\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='20' height='20' fill='none'><path d='M9.99935 18.3327C14.6017 18.3327 18.3327 14.6017 18.3327 9.99935C18.3327 5.39698 14.6017 1.66602 9.99935 1.66602C5.39698 1.66602 1.66602 5.39698 1.66602 9.99935C1.66602 14.6017 5.39698 18.3327 9.99935 18.3327Z' stroke='currentColor' stroke-width='1.5' stroke-linecap='round' stroke-linejoin='round' \/><path d='M10 6.66602V9.99935' stroke='currentColor' stroke-width='1.5' stroke-linecap='round' stroke-linejoin='round' \/><path d='M10 13.334H10.0083' stroke='currentColor' stroke-width='1.5' stroke-linecap='round' stroke-linejoin='round' \/><\/svg>\t\t<\/span>\n\t\t<span class=\"srfm-error-content\">There was an error trying to submit your form. Please try again.<\/span><\/p>\n\t\t\t\t\t<\/form>\n\t\t\t<div class=\"srfm-single-form srfm-success-box in-page\">\n\t\t\t\t<div aria-live=\"polite\" aria-atomic=\"true\" role=\"alert\" id=\"srfm-success-message-page-334\" class=\"srfm-success-box-description\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fe8ae009 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-5b47e45b\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ed4b3636\"><h2 class=\"uagb-heading-text\">LOKASI KAMI<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ec26736e\"><h2 class=\"uagb-heading-text\">Temukan Kami di Google<\/h2><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-314d4e08 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-1a6b86d2\">\n<div class=\"wp-block-uagb-container uagb-block-4782d039\">\n<div class=\"wp-block-uagb-info-box uagb-block-a440c689 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M168.3 499.2C116.1 435 0 279.4 0 192C0 85.96 85.96 0 192 0C298 0 384 85.96 384 192C384 279.4 267 435 215.7 499.2C203.4 514.5 180.6 514.5 168.3 499.2H168.3zM192 256C227.3 256 256 227.3 256 192C256 156.7 227.3 128 192 128C156.7 128 128 156.7 128 192C128 227.3 156.7 256 192 256z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Alamat<\/h6><\/div><p class=\"uagb-ifb-desc\">Jl. Laut No. 25C Kendal 51311<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d5ea53b7\">\n<div class=\"wp-block-uagb-info-box uagb-block-35dcb393 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M464 64C490.5 64 512 85.49 512 112C512 127.1 504.9 141.3 492.8 150.4L275.2 313.6C263.8 322.1 248.2 322.1 236.8 313.6L19.2 150.4C7.113 141.3 0 127.1 0 112C0 85.49 21.49 64 48 64H464zM217.6 339.2C240.4 356.3 271.6 356.3 294.4 339.2L512 176V384C512 419.3 483.3 448 448 448H64C28.65 448 0 419.3 0 384V176L217.6 339.2z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Email<\/h6><\/div><p class=\"uagb-ifb-desc\">disperkimkendal.it@gmail.com<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4b55f7de\">\n<div class=\"wp-block-uagb-info-box uagb-block-fd885d7c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M511.2 387l-23.25 100.8c-3.266 14.25-15.79 24.22-30.46 24.22C205.2 512 0 306.8 0 54.5c0-14.66 9.969-27.2 24.22-30.45l100.8-23.25C139.7-2.602 154.7 5.018 160.8 18.92l46.52 108.5c5.438 12.78 1.77 27.67-8.98 36.45L144.5 207.1c33.98 69.22 90.26 125.5 159.5 159.5l44.08-53.8c8.688-10.78 23.69-14.51 36.47-8.975l108.5 46.51C506.1 357.2 514.6 372.4 511.2 387z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Telepon<\/h6><\/div><p class=\"uagb-ifb-desc\">(0294) 381395<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a31fb8fe\">\n<div class=\"wp-block-uagb-info-box uagb-block-6f69f03e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M503.7 226.2l-176 151.1c-15.38 13.3-39.69 2.545-39.69-18.16V272.1C132.9 274.3 66.06 312.8 111.4 457.8c5.031 16.09-14.41 28.56-28.06 18.62C39.59 444.6 0 383.8 0 322.3c0-152.2 127.4-184.4 288-186.3V56.02c0-20.67 24.28-31.46 39.69-18.16l176 151.1C514.8 199.4 514.8 216.6 503.7 226.2z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Follow<\/h6><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share uagb-social-share__outer-wrap uagb-social-share__layout-horizontal uagb-block-13fa4fdc uag-hide-desktop uag-hide-tab uag-hide-mob\">\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-03466d9f\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.facebook.com\/sharer.php?u=\" tabindex=\"0\" role=\"button\" aria-label=\"facebook\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.8 90.69 226.4 209.3 245V327.7h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.3 482.4 504 379.8 504 256z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-5eb4e684\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/twitter.com\/share?url=\" tabindex=\"0\" role=\"button\" aria-label=\"twitter\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-4c6dae03\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/pinterest.com\/pin\/create\/link\/?url=\" tabindex=\"0\" role=\"button\" aria-label=\"pinterest\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path d=\"M549.7 124.1c-6.281-23.65-24.79-42.28-48.28-48.6C458.8 64 288 64 288 64S117.2 64 74.63 75.49c-23.5 6.322-42 24.95-48.28 48.6-11.41 42.87-11.41 132.3-11.41 132.3s0 89.44 11.41 132.3c6.281 23.65 24.79 41.5 48.28 47.82C117.2 448 288 448 288 448s170.8 0 213.4-11.49c23.5-6.321 42-24.17 48.28-47.82 11.41-42.87 11.41-132.3 11.41-132.3s0-89.44-11.41-132.3zm-317.5 213.5V175.2l142.7 81.21-142.7 81.2z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-63fd8c0c\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.linkedin.com\/shareArticle?url=\" tabindex=\"0\" role=\"button\" aria-label=\"linkedin\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1dffb6d2\">\n<div class=\"wp-block-uagb-info-box uagb-block-386706f5 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/www.facebook.com\/disperkim.kendal.39\/\" target=\"_self\" onclick=\"return true;\" class=\"uagb-infobox-cta-link\" rel=\"noopener noreferrer\"><span class=\"uagb-inline-editing\"><\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 320 512\"><path d=\"M279.1 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.4 0 225.4 0c-73.22 0-121.1 44.38-121.1 124.7v70.62H22.89V288h81.39v224h100.2V288z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-59af7623 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/www.instagram.com\/disperkim_kendal\/\" target=\"_self\" onclick=\"return true;\" class=\"uagb-infobox-cta-link\" rel=\"noopener noreferrer\"><span class=\"uagb-inline-editing\"><\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\t\t\t<div \n\t\t\tclass=\"wp-block-uagb-google-map uagb-google-map__wrap uagb-block-be9b46a0     \"\n\t\t\tstyle=\"\" >\n\t\t\t\t<embed\n\t\t\t\t\tclass=\"uagb-google-map__iframe\"\n\t\t\t\t\ttitle=\"Google Map for \"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Jl.%20Laut%20No.25%20C%2C%20RT.02%2FRW.5%2C%20Ngilir%2C%20Kec.%20Kendal%2C%20Kabupaten%20Kendal%2C%20Jawa%20Tengah%2051311&#038;z=15&#038;hl=en&#038;t=m&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\twidth=\"640\"\n\t\t\t\t\theight=\"440\"\n\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t><\/embed>\n\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kontak Kami Siap Membantu LOKASI KAMI Temukan Kami di Google<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"spectra_custom_meta":{"site-sidebar-layout":["no-sidebar"],"ast-site-content-layout":["full-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"site-post-title":["disabled"],"theme-transparent-header-meta":["enabled"],"astra-migrate-meta-layouts":["default"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"astra-main-page-id":["110802"],"ast_self_id_110802":["1"],"_wxr_import_user_slug":["devanshus"],"_astra_sites_imported_post":["1"],"_astra_sites_enable_for_batch":["1"],"_edit_lock":["1764840720:1"],"_edit_last":["1"],"_ahcfree_total_views":["3"],"_ahcfree_unique_visitors":["3"],"_uag_css_file_name":["uag-css-14.css"],"_uag_js_file_name":["uag-js-14.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:253306:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-star-rating{display:flex}.wp-block-uagb-star-rating .uag-star-rating__title{margin:0}.wp-block-uagb-star-rating .uag-star-rating{display:flex;align-items:center}.wp-block-uagb-star-rating .uag-star{color:#ccd6df;display:inline-block;line-height:.75em}.uagb-social-share__outer-wrap,.uagb-social-share__wrap{display:flex;align-items:center;justify-content:center}.uagb-social-share__layout-vertical.uagb-social-share__outer-wrap,.uagb-social-share__layout-vertical .uagb-social-share__wrap{flex-direction:column}.uagb-social-share__layout-vertical .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:first-child{margin-top:0 !important}.uagb-social-share__layout-vertical .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:last-child{margin-bottom:0 !important}.uagb-social-share__outer-wrap a.uagb-button__link:focus{box-shadow:none}.uagb-social-share__outer-wrap .uagb-ss__wrapper{padding:0;margin-left:5px;margin-right:5px;transition:all .2s;display:inline-flex;text-align:center}.uagb-social-share__outer-wrap .uagb-ss__source-wrap{display:inline-block}.uagb-social-share__outer-wrap .uagb-ss__link{color:#3a3a3a;display:inline-table;line-height:0;cursor:pointer}.uagb-social-share__outer-wrap .uagb-ss__source-icon{font-size:40px;width:40px;height:40px}.uagb-social-share__outer-wrap .uagb-ss__source-image{width:40px}@media(max-width: 976px){.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left:0;margin-right:0}}.uagb-social-share__layout-horizontal .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:first-child{margin-left:0 !important}.uagb-social-share__layout-horizontal .wp-block-uagb-social-share-child.uagb-ss-repeater.uagb-ss__wrapper:last-child{margin-right:0 !important}.wp-block-uagb-social-share .uagb-social-share__wrapper{text-decoration:none}.uagb-social-share__wrapper{box-shadow:none}.uagb-social-share__outer-wrap:not(.uagb-social-share__no-label) .uagb-social-share__source-wrap{margin-right:15px}.uagb-social-share__outer-wrap.uagb-social-share__icon-at-top .uagb-social-share__source-wrap{-ms-flex-item-align:flex-start;align-self:flex-start;margin-top:5px}.uagb-google-map__wrap{display:flex}.uagb-google-map__wrap .uagb-google-map__iframe{width:100%;box-shadow:none;border:none;padding:0;margin:0}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape-bottom svg{height: 106px;width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: var(--ast-global-color-4);}.wp-block-uagb-container.uagb-block-fdff1306 .uagb-container__video-wrap video{opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdff1306{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdff1306 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fdff1306{box-shadow: 0px 0px   #00000070 ;padding-top: 200px;padding-bottom: 200px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/ga5e927ea17856cde1a06174858359fe113adff16660b99a4284c5a9283211ad5b9a49b297fdd3707a26c3f8ead2c79e021c9e7d6fb4350c7c2245d0163c2d2a6_1280-9298784.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fdff1306::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-2);opacity: 0.8;}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ea1cf1b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ea1cf1b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ea1cf1b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2ea1cf1b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c65b938f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c65b938f{max-width: 7%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c65b938f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c65b938f{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 2px;padding-bottom: 2px;padding-left: 1px;padding-right: 1px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 99px;border-top-right-radius: 99px;border-bottom-left-radius: 99px;border-bottom-right-radius: 99px;border-color: inherit;background-color: rgba(255,255,255,0.14);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-99f1bb67.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-bf9c0f05 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-bf9c0f05 .uagb-ifb-icon svg{fill: #333;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf9c0f05 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf9c0f05 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf9c0f05 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 10px;margin-top: 0px;margin-left: 170px;margin-right: 170px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 240px;margin-right: 240px;}.uagb-block-bf9c0f05 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-bf9c0f05 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-bf9c0f05 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-bf9c0f05 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf9c0f05 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-bf9c0f05.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-cacb9c7b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cacb9c7b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cacb9c7b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-cacb9c7b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-cacb9c7b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cacb9c7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cacb9c7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-cacb9c7b{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4cdcc25f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4cdcc25f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4cdcc25f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4cdcc25f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4cdcc25f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4cdcc25f{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4cdcc25f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 2px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4cdcc25f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 2px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40 .uagb-heading-text{text-transform: uppercase;font-weight: 600;font-size: 14px;letter-spacing: 2px;}.uagb-block-1d2e6ada .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d2e6ada .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-1d2e6ada .uagb-ifb-icon svg{fill: #333;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d2e6ada .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d2e6ada .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d2e6ada .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d2e6ada .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-1d2e6ada.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 60px;}.uagb-block-1d2e6ada.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 40px;margin-top: 0px;margin-left: 0px;margin-right: 24px;}.uagb-block-1d2e6ada .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-1d2e6ada .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-1d2e6ada .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-1d2e6ada .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d2e6ada .uagb-infobox__content-wrap{text-align: left;}.uagb-block-1d2e6ada.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d2e6ada .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-9a4f633f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a4f633f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a4f633f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a4f633f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a4f633f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a4f633f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a4f633f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9a4f633f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-93a311ce .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-93a311ce .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-93a311ce .uagb-ifb-icon svg{fill: #333;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-93a311ce .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-93a311ce .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-93a311ce .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-93a311ce .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-93a311ce.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;}.uagb-block-93a311ce.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-93a311ce .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-93a311ce .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-93a311ce .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-93a311ce .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-93a311ce .uagb-infobox__content-wrap{text-align: left;}.uagb-block-93a311ce.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-93a311ce.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-93a311ce .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6ec30441 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6ec30441 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-6ec30441 .uagb-ifb-icon svg{fill: #333;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6ec30441 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6ec30441 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6ec30441 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6ec30441 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6ec30441.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-6ec30441.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-6ec30441 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6ec30441 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6ec30441 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6ec30441 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6ec30441 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-6ec30441.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6ec30441 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-622f196b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-622f196b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-622f196b .uagb-ifb-icon svg{fill: #333;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-622f196b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-622f196b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-622f196b .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-622f196b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-622f196b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-622f196b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-622f196b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-622f196b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-622f196b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-622f196b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-622f196b .uagb-infobox__content-wrap{text-align: left;}.uagb-block-622f196b.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-622f196b .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-622f196b.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f35f5c8a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f35f5c8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f35f5c8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f35f5c8a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4960d791 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4960d791 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4960d791 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4960d791 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4960d791 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4960d791{max-width: 16%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4960d791 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4960d791{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-1c697a61.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-1c697a61 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-1c697a61.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-1c697a61.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1c697a61.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;} .uagb-block-ff661e74 .uag-star-rating{font-size: 20px;} .uagb-block-ff661e74 .uag-star-rating > span{margin-right: 4px;color: #ccd6df;} .uagb-block-ff661e74 .uag-star:nth-child(-n+4){color: #f0ad4e;} .uagb-block-ff661e74 .uag-star-rating__title{margin-top: 8px;} .uagb-block-ff661e74.wp-block-uagb-star-rating{flex-direction: column-reverse;align-items: flex-start;} .uagb-block-ff661e74 .uag-star:nth-child(5):before{color: #f0ad4e;width: 90%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-ff661e74 .uag-star:nth-child(5){position: relative;}.wp-block-uagb-container.uagb-block-c2bb3c7e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c2bb3c7e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c2bb3c7e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c2bb3c7e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c2bb3c7e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c2bb3c7e{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c2bb3c7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c2bb3c7e{box-shadow: 0px 50px 50px -30px rgba(0,0,0,0.09) ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fe8ae009 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe8ae009{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe8ae009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 80px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fe8ae009{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 80px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b47e45b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b47e45b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b47e45b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 8px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5b47e45b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 8px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ed4b3636 .uagb-heading-text{text-transform: uppercase;font-weight: 600;font-size: 14px;letter-spacing: 2px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ec26736e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-314d4e08 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-314d4e08 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-314d4e08 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-314d4e08 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-314d4e08 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-314d4e08{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-314d4e08 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-314d4e08{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1a6b86d2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1a6b86d2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1a6b86d2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1a6b86d2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1a6b86d2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a6b86d2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1a6b86d2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1a6b86d2.uagb-layout-grid{row-gap: 20px;column-gap: 20px;grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-1a6b86d2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4782d039 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4782d039{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4782d039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4782d039{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-a440c689 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-a440c689 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-a440c689 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-a440c689 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-a440c689 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-a440c689.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-a440c689.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 8px;margin-left: 0px;margin-right: 0px;}.uagb-block-a440c689 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-a440c689 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-a440c689 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-a440c689 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a440c689.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-a440c689 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-2);border-radius: 50%;}.uagb-block-a440c689 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-2);}.uagb-block-a440c689 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-a440c689 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-a440c689.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-a440c689.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a440c689 .uagb-iconbox-icon-wrap{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-a440c689.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5ea53b7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5ea53b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d5ea53b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d5ea53b7{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-35dcb393 .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-35dcb393 .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-35dcb393 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-35dcb393 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-35dcb393 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-35dcb393.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-35dcb393.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 8px;margin-left: 0px;margin-right: 0px;}.uagb-block-35dcb393 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-35dcb393 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-35dcb393 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-35dcb393 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-35dcb393.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-2);border-radius: 50%;}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-2);}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-35dcb393 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-35dcb393.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-35dcb393.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-35dcb393 .uagb-iconbox-icon-wrap{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-4b55f7de .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4b55f7de .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4b55f7de .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4b55f7de .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4b55f7de .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4b55f7de{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4b55f7de > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4b55f7de{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-fd885d7c .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-fd885d7c .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-fd885d7c .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-fd885d7c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-fd885d7c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-fd885d7c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-fd885d7c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fd885d7c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-fd885d7c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 8px;margin-left: 0px;margin-right: 0px;}.uagb-block-fd885d7c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fd885d7c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fd885d7c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fd885d7c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fd885d7c.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-fd885d7c .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-2);border-radius: 50%;}.uagb-block-fd885d7c .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-2);}.uagb-block-fd885d7c .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-fd885d7c .uagb-infobox__content-wrap{text-align: center;}.uagb-block-fd885d7c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-fd885d7c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fd885d7c .uagb-iconbox-icon-wrap{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-a31fb8fe .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a31fb8fe .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a31fb8fe .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a31fb8fe .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a31fb8fe .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a31fb8fe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a31fb8fe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a31fb8fe{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.uagb-block-6f69f03e .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-6f69f03e .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: var(--ast-global-color-0);}.uagb-block-6f69f03e .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-6f69f03e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-6f69f03e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;}.uagb-block-6f69f03e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 16px;padding-right: 16px;padding-top: 16px;padding-bottom: 16px;border-radius: 0px;}.uagb-block-6f69f03e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6f69f03e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-6f69f03e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 8px;margin-left: 0px;margin-right: 0px;}.uagb-block-6f69f03e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6f69f03e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6f69f03e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6f69f03e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6f69f03e.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-6f69f03e .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-2);border-radius: 50%;}.uagb-block-6f69f03e .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-2);}.uagb-block-6f69f03e .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-6f69f03e .uagb-infobox__content-wrap{text-align: center;}.uagb-block-6f69f03e.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-6f69f03e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6f69f03e .uagb-iconbox-icon-wrap{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 16px;padding-left: 16px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-13fa4fdc .uagb-ss-repeater span.uagb-ss__link{color: #3a3a3a;}.uagb-block-13fa4fdc .uagb-ss-repeater a.uagb-ss__link{color: #3a3a3a;}.uagb-block-13fa4fdc .uagb-ss-repeater span.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-13fa4fdc .uagb-ss-repeater a.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-13fa4fdc.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 4px;margin-bottom: 4px;}.uagb-block-13fa4fdc.uagb-social-share__layout-vertical .uagb-ss__link{padding: 8px;}.uagb-block-13fa4fdc.uagb-social-share__layout-horizontal .uagb-ss__link{padding: 8px;}.uagb-block-13fa4fdc.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 4px;margin-right: 4px;}.uagb-block-13fa4fdc .wp-block-uagb-social-share-child {border-radius: 0px;}.uagb-block-13fa4fdc .uagb-ss__source-wrap{width: 18px;}.uagb-block-13fa4fdc .uagb-ss__source-wrap svg{width: 18px;height: 18px;}.uagb-block-13fa4fdc .uagb-ss__source-image{width: 18px;}.uagb-block-13fa4fdc .uagb-ss__source-icon{width: 18px;height: 18px;font-size: 18px;}.uagb-block-13fa4fdc.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-03466d9f.uagb-ss-repeater span.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-03466d9f.uagb-ss-repeater a.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-03466d9f.uagb-ss-repeater span.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-03466d9f.uagb-ss-repeater a.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-03466d9f.uagb-ss-repeater:hover span.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-03466d9f.uagb-ss-repeater:hover a.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-03466d9f.uagb-ss-repeater:hover span.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-03466d9f.uagb-ss-repeater:hover a.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-5eb4e684.uagb-ss-repeater span.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-5eb4e684.uagb-ss-repeater a.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-5eb4e684.uagb-ss-repeater span.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-5eb4e684.uagb-ss-repeater a.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-5eb4e684.uagb-ss-repeater:hover span.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-5eb4e684.uagb-ss-repeater:hover a.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-5eb4e684.uagb-ss-repeater:hover span.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-5eb4e684.uagb-ss-repeater:hover a.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-4c6dae03.uagb-ss-repeater span.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-4c6dae03.uagb-ss-repeater a.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-4c6dae03.uagb-ss-repeater span.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-4c6dae03.uagb-ss-repeater a.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-4c6dae03.uagb-ss-repeater:hover span.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-4c6dae03.uagb-ss-repeater:hover a.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-4c6dae03.uagb-ss-repeater:hover span.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-4c6dae03.uagb-ss-repeater:hover a.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-63fd8c0c.uagb-ss-repeater span.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-63fd8c0c.uagb-ss-repeater a.uagb-ss__link{color: var(--ast-global-color-2);}.uagb-block-63fd8c0c.uagb-ss-repeater span.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-63fd8c0c.uagb-ss-repeater a.uagb-ss__link svg{fill: var(--ast-global-color-2);}.uagb-block-63fd8c0c.uagb-ss-repeater:hover span.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-63fd8c0c.uagb-ss-repeater:hover a.uagb-ss__link{color: var(--ast-global-color-3);}.uagb-block-63fd8c0c.uagb-ss-repeater:hover span.uagb-ss__link svg{fill: var(--ast-global-color-3);}.uagb-block-63fd8c0c.uagb-ss-repeater:hover a.uagb-ss__link svg{fill: var(--ast-global-color-3);}.wp-block-uagb-container.uagb-block-1dffb6d2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1dffb6d2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1dffb6d2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1dffb6d2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1dffb6d2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1dffb6d2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1dffb6d2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 16px;}.wp-block-uagb-container.uagb-block-1dffb6d2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 16px;}.wp-block-uagb-container.uagb-block-1dffb6d2.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-1dffb6d2.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.uagb-block-386706f5 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-386706f5 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-386706f5 .uagb-ifb-icon svg{fill: #333;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-386706f5 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-386706f5 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-386706f5 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-386706f5.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-386706f5 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-386706f5.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-386706f5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-386706f5 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-386706f5 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-386706f5 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-386706f5 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-386706f5 div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link{color: var(--ast-global-color-2);}.uagb-block-386706f5 div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link:hover{color: var(--ast-global-color-3);}.uagb-block-386706f5 div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link:focus{color: var(--ast-global-color-3);}.uagb-block-386706f5 .uagb-infobox-cta-link:hover svg{fill: var(--ast-global-color-3);}.uagb-block-386706f5 .uagb-infobox-cta-link:focus svg{fill: var(--ast-global-color-3);}.uagb-block-386706f5 .uagb-infobox-cta-link svg{font-size: 18px;height: 18px;width: 18px;line-height: 18px;fill: var(--ast-global-color-2);}.uagb-block-386706f5 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-386706f5.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-386706f5 .uagb-infobox-cta-link{font-size: 18px;}[dir=rtl] .uagb-block-386706f5 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-386706f5.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-59af7623 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-59af7623 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-59af7623 .uagb-ifb-icon svg{fill: #333;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-59af7623 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-59af7623 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-59af7623 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-59af7623.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-59af7623 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-59af7623.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-59af7623.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-59af7623 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-59af7623 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-59af7623 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-59af7623 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-59af7623 div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link{color: var(--ast-global-color-2);}.uagb-block-59af7623 div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link:hover{color: var(--ast-global-color-3);}.uagb-block-59af7623 div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link:focus{color: var(--ast-global-color-3);}.uagb-block-59af7623 .uagb-infobox-cta-link:hover svg{fill: var(--ast-global-color-3);}.uagb-block-59af7623 .uagb-infobox-cta-link:focus svg{fill: var(--ast-global-color-3);}.uagb-block-59af7623 .uagb-infobox-cta-link svg{font-size: 18px;height: 18px;width: 18px;line-height: 18px;fill: var(--ast-global-color-2);}.uagb-block-59af7623 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-59af7623.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-59af7623 .uagb-infobox-cta-link{font-size: 18px;}[dir=rtl] .uagb-block-59af7623 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-59af7623.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;} .uagb-block-be9b46a0 .uagb-google-map__iframe{height: 440px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdff1306{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdff1306 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fdff1306{padding-top: 120px;padding-bottom: 120px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/ga5e927ea17856cde1a06174858359fe113adff16660b99a4284c5a9283211ad5b9a49b297fdd3707a26c3f8ead2c79e021c9e7d6fb4350c7c2245d0163c2d2a6_1280-9298784.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-fdff1306::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-2);opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ea1cf1b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ea1cf1b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2ea1cf1b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c65b938f{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c65b938f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c65b938f{padding-top: 2px;padding-bottom: 2px;padding-left: 1px;padding-right: 1px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: rgba(255,255,255,0.14);;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 80px;margin-right: 80px;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf9c0f05 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cacb9c7b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cacb9c7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;row-gap: 40px;}.wp-block-uagb-container.uagb-block-cacb9c7b{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 40px;}.wp-block-uagb-container.uagb-block-cacb9c7b.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-cacb9c7b.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4cdcc25f{max-width: 77%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4cdcc25f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;}.wp-block-uagb-container.uagb-block-4cdcc25f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: flex-start;}.wp-block-uagb-advanced-heading.uagb-block-27ca6c40.wp-block-uagb-advanced-heading {text-align: left;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d2e6ada .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d2e6ada .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1d2e6ada .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a4f633f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a4f633f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9a4f633f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-93a311ce .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-93a311ce .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-93a311ce .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6ec30441 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6ec30441 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6ec30441 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-622f196b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-622f196b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-622f196b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f35f5c8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f35f5c8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f35f5c8a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: flex-start;row-gap: 3px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f35f5c8a.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-f35f5c8a.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4960d791{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4960d791 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4960d791{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;} .uagb-block-ff661e74.wp-block-uagb-star-rating{flex-direction: column-reverse;align-items: flex-start;} .uagb-block-ff661e74 .uag-star-rating__title{margin-top: 10px;} .uagb-block-ff661e74 .uag-star-rating{font-size: 18px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c2bb3c7e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c2bb3c7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;}.wp-block-uagb-container.uagb-block-c2bb3c7e{padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe8ae009{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe8ae009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;}.wp-block-uagb-container.uagb-block-fe8ae009{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;row-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b47e45b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b47e45b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5b47e45b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-314d4e08{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-314d4e08 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-314d4e08{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a6b86d2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1a6b86d2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1a6b86d2.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-1a6b86d2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4782d039{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4782d039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4782d039{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689.uagb-infobox__content-wrap > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689 .uagb-ifb-content > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689 .uagb-infobox-icon-right:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689 .uagb-infobox-icon-left:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689.uagb-infobox__content-wrap img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a440c689 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-a440c689 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-a440c689 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-a440c689.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689 .uagb-ifb-content > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689 .uagb-infobox-icon-right:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689 .uagb-infobox-icon-left:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5ea53b7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d5ea53b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d5ea53b7{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393.uagb-infobox__content-wrap > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393 .uagb-ifb-content > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393 .uagb-infobox-icon-right:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393 .uagb-infobox-icon-left:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393.uagb-infobox__content-wrap img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-35dcb393 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-35dcb393 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-35dcb393.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393 .uagb-ifb-content > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393 .uagb-infobox-icon-right:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393 .uagb-infobox-icon-left:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4b55f7de{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4b55f7de > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4b55f7de{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c .uagb-ifb-content > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c .uagb-infobox-icon-right:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c .uagb-infobox-icon-left:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fd885d7c .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-fd885d7c .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-fd885d7c .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c .uagb-ifb-content > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c .uagb-infobox-icon-right:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c .uagb-infobox-icon-left:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a31fb8fe{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a31fb8fe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 2px;}.wp-block-uagb-container.uagb-block-a31fb8fe{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;row-gap: 2px;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e .uagb-ifb-content > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e .uagb-infobox-icon-right:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e .uagb-infobox-icon-left:hover > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6f69f03e .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-6f69f03e .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-6f69f03e .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e .uagb-ifb-content > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e .uagb-infobox-icon-right:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e .uagb-infobox-icon-left:hover > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-13fa4fdc.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 4px;margin-bottom: 4px;}.uagb-block-13fa4fdc.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 4px;margin-right: 4px;}.uagb-block-13fa4fdc.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1dffb6d2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1dffb6d2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1dffb6d2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-386706f5 .uagb-infobox-cta-link svg{font-size: 18px;height: 18px;width: 18px;line-height: 18px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-386706f5 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-386706f5 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-386706f5 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-59af7623 .uagb-infobox-cta-link svg{font-size: 18px;height: 18px;width: 18px;line-height: 18px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-59af7623 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-59af7623 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-59af7623 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;} .uagb-block-be9b46a0 .uagb-google-map__iframe{height: 300px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdff1306{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdff1306 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fdff1306{padding-top: 120px;padding-bottom: 120px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/instaframer.com\/dinaspu\/wp-content\/uploads\/2025\/07\/ga5e927ea17856cde1a06174858359fe113adff16660b99a4284c5a9283211ad5b9a49b297fdd3707a26c3f8ead2c79e021c9e7d6fb4350c7c2245d0163c2d2a6_1280-9298784.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-fdff1306::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-2);opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ea1cf1b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ea1cf1b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2ea1cf1b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c65b938f{max-width: 28%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c65b938f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c65b938f{padding-top: 2px;padding-bottom: 2px;padding-left: 1px;padding-right: 1px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: rgba(255,255,255,0.14);;flex-wrap: wrap;}.uagb-block-bf9c0f05.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf9c0f05 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bf9c0f05 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf9c0f05.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-cacb9c7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-cacb9c7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-cacb9c7b{padding-top: 60px;padding-bottom: 60px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;row-gap: 40px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4cdcc25f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4cdcc25f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4cdcc25f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-1d2e6ada.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d2e6ada .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d2e6ada .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1d2e6ada .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d2e6ada.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a4f633f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a4f633f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9a4f633f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-93a311ce .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-93a311ce .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-93a311ce .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-93a311ce .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-93a311ce.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6ec30441 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6ec30441 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6ec30441 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6ec30441 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6ec30441.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-622f196b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-622f196b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-622f196b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-622f196b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-622f196b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-622f196b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f35f5c8a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f35f5c8a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;justify-content: flex-start;flex-wrap: wrap;row-gap: 18px;}.wp-block-uagb-container.uagb-block-f35f5c8a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 18px;order: initial;flex-direction: row;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f35f5c8a.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-f35f5c8a.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4960d791{max-width: 16%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4960d791 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;justify-content: flex-start;flex-wrap: wrap;align-content: flex-start;}.wp-block-uagb-container.uagb-block-4960d791{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;justify-content: flex-start;flex-wrap: wrap;align-content: flex-start;}.uagb-block-1c697a61.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-1c697a61.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-1c697a61 .wp-block-uagb-image__figure{align-items: flex-start;} .uagb-block-ff661e74.wp-block-uagb-star-rating{flex-direction: column-reverse;align-items: flex-start;padding-bottom: 0px;} .uagb-block-ff661e74 .uag-star-rating__title{margin-top: 10px;} .uagb-block-ff661e74 .uag-star-rating{font-size: 18px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c2bb3c7e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c2bb3c7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c2bb3c7e{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fe8ae009{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fe8ae009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-fe8ae009{padding-top: 60px;padding-bottom: 80px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;row-gap: 40px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b47e45b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b47e45b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5b47e45b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-314d4e08{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-314d4e08 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-314d4e08{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a6b86d2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1a6b86d2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1a6b86d2.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-1a6b86d2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4782d039{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4782d039 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4782d039{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-a440c689 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a440c689 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-a440c689 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-a440c689 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-a440c689.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a440c689.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5ea53b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d5ea53b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d5ea53b7{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-35dcb393 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-35dcb393 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-35dcb393 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-35dcb393 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-35dcb393.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-35dcb393.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4b55f7de{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4b55f7de > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4b55f7de{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-fd885d7c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fd885d7c .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-fd885d7c .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-fd885d7c .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-fd885d7c.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fd885d7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a31fb8fe{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a31fb8fe > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a31fb8fe{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;flex-wrap: wrap;grid-column: span 1;grid-row: span 1;align-self: stretch;justify-self: stretch;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-6f69f03e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6f69f03e .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-6f69f03e .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-6f69f03e .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-6f69f03e.uagb-infobox__content-wrap{border-style: none;border-color: var(--ast-global-color-6);}.uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6f69f03e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-13fa4fdc.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 4px;margin-bottom: 4px;}.uagb-block-13fa4fdc.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 4px;margin-right: 4px;}.uagb-block-13fa4fdc.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1dffb6d2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1dffb6d2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1dffb6d2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-386706f5 .uagb-infobox-cta-link svg{font-size: 18px;height: 18px;width: 18px;line-height: 18px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-386706f5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-386706f5 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-386706f5 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-386706f5 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-386706f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-386706f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-59af7623 .uagb-infobox-cta-link svg{font-size: 18px;height: 18px;width: 18px;line-height: 18px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-59af7623 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-59af7623 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-59af7623 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-59af7623 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-59af7623.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-59af7623.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;} .uagb-block-be9b46a0 .uagb-google-map__iframe{height: 300px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e5f40570 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e5f40570{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e5f40570 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 44px;}.wp-block-uagb-container.uagb-block-e5f40570{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 60px;padding-right: 60px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 24px;border-top-right-radius: 24px;border-bottom-left-radius: 24px;border-bottom-right-radius: 24px;border-color: inherit;background-color: var(--ast-global-color-0);;row-gap: 20px;column-gap: 44px;}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c7e1a1ce .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7e1a1ce{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7e1a1ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c7e1a1ce{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 100px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-34a517cb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34a517cb{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34a517cb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-34a517cb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-75a92e01 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-75a92e01 .uagb-ifb-icon svg{fill: #333;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-75a92e01 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75a92e01 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-75a92e01 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-75a92e01.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-75a92e01.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 16px;}.uagb-block-75a92e01 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-75a92e01 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-75a92e01 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-75a92e01 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75a92e01 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-75a92e01.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75a92e01.wp-block-uagb-info-box .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{color: var(--ast-global-color-0);background-color: var(--ast-global-color-7);}.uagb-block-75a92e01.wp-block-uagb-info-box.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{color: var(--ast-global-color-0);background-color: var(--ast-global-color-7);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: #333;border-style: none;}.uagb-block-75a92e01 .uagb-ifb-button-wrapper .uagb-infobox-cta-link svg{fill: var(--ast-global-color-0);}.uagb-block-75a92e01 .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: #333;border-style: none;}[dir=rtl] .uagb-block-75a92e01 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e5f40570{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e5f40570 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e5f40570{padding-top: 40px;padding-bottom: 40px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-0);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7e1a1ce{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7e1a1ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c7e1a1ce{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34a517cb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34a517cb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-34a517cb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75a92e01 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75a92e01 .uagb-infobox-cta-link{border-style: none;border-color: #333;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e5f40570{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e5f40570 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e5f40570{padding-top: 32px;padding-bottom: 32px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-0);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c7e1a1ce{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c7e1a1ce > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c7e1a1ce{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-fe9935be.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34a517cb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34a517cb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-34a517cb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75a92e01 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-75a92e01 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75a92e01 .uagb-infobox-cta-link{border-style: none;border-color: #333;}[dir=rtl] .uagb-block-75a92e01.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-211a6307 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-211a6307{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-211a6307 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-211a6307{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-block-73fe9699.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-73fe9699 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-73fe9699.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: 107px;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-73fe9699.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-73fe9699.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-211a6307{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-211a6307 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-211a6307{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-211a6307{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-211a6307 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-211a6307{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-73fe9699.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-07791abd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-07791abd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-07791abd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-07791abd{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-07791abd{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-07791abd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-07791abd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-07791abd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-07791abd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-07791abd{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-40c1039e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-heading-text{color: #fefefe;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3b437bb.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-88ced37a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-icon svg{width:30px}.uagb-icon-wrapper .uagb-svg-wrapper{transition:box-shadow .2s ease}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdbc477e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdbc477e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdbc477e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-fdbc477e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-915a0751 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-915a0751{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-915a0751 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-915a0751{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;} .uagb-block-d54b4f1a.uagb-icon-wrapper{text-align: left;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-d54b4f1a.uagb-icon-wrapper svg{width: 12px;height: 12px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-7);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;background: var(--ast-global-color-0);padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;box-shadow: 0px 0px 0 #00000070 ;border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ab3b6093 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab3b6093{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab3b6093 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ab3b6093{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-98bbd9c1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-98bbd9c1 .uagb-ifb-icon svg{fill: #333;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-98bbd9c1 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-98bbd9c1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-98bbd9c1.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 2px;}.uagb-block-98bbd9c1.wp-block-uagb-info-box .uagb-ifb-desc{color: rgba(255,255,255,0.74);margin-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-98bbd9c1 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-98bbd9c1 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-98bbd9c1 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-98bbd9c1 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-98bbd9c1.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-98bbd9c1 .uagb-ifb-title{font-weight: 900;font-size: 16px;}[dir=rtl] .uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdbc477e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdbc477e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fdbc477e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-915a0751{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-915a0751 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-915a0751{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab3b6093{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab3b6093 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ab3b6093{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-98bbd9c1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdbc477e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdbc477e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fdbc477e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-915a0751{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-915a0751 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-915a0751{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;} .uagb-block-d54b4f1a.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ab3b6093{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ab3b6093 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ab3b6093{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-98bbd9c1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-98bbd9c1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-98bbd9c1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c212dd68 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c212dd68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c212dd68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c212dd68{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-797ec235 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-797ec235{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-797ec235 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-797ec235{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;} .uagb-block-4d869d83.uagb-icon-wrapper{text-align: left;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-4d869d83.uagb-icon-wrapper svg{width: 12px;height: 12px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-7);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;background: var(--ast-global-color-0);padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;box-shadow: 0px 0px 0 #00000070 ;border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-af66883b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af66883b{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af66883b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-af66883b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-e7e7f750 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e7e7f750 .uagb-ifb-icon svg{fill: #333;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e7e7f750 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e7e7f750 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e7e7f750 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e7e7f750.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 2px;}.uagb-block-e7e7f750.wp-block-uagb-info-box .uagb-ifb-desc{color: rgba(255,255,255,0.74);margin-bottom: 0px;}.uagb-block-e7e7f750 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e7e7f750 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e7e7f750 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e7e7f750 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e7e7f750 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-e7e7f750.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e7e7f750 .uagb-ifb-title{font-weight: 900;font-size: 16px;}[dir=rtl] .uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c212dd68{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c212dd68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c212dd68{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-797ec235{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-797ec235 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-797ec235{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af66883b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af66883b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-af66883b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e7e7f750 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c212dd68{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c212dd68 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c212dd68{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-797ec235{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-797ec235 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-797ec235{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;} .uagb-block-4d869d83.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-af66883b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-af66883b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-af66883b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e7e7f750 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e7e7f750 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e7e7f750.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4ed6bcbf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4ed6bcbf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4ed6bcbf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4ed6bcbf{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eb563004 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb563004{max-width: 10%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb563004 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eb563004{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;} .uagb-block-f286b3bf.uagb-icon-wrapper{text-align: left;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-f286b3bf.uagb-icon-wrapper svg{width: 12px;height: 12px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-7);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;background: var(--ast-global-color-0);padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;box-shadow: 0px 0px 0 #00000070 ;border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d1acc551 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d1acc551{max-width: 80%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d1acc551 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d1acc551{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-1d6b19b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-1d6b19b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1d6b19b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1d6b19b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-1d6b19b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 2px;}.uagb-block-1d6b19b8.wp-block-uagb-info-box .uagb-ifb-desc{color: rgba(255,255,255,0.74);margin-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-1d6b19b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-1d6b19b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-1d6b19b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d6b19b8 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-1d6b19b8.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-1d6b19b8 .uagb-ifb-title{font-weight: 900;font-size: 16px;}[dir=rtl] .uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4ed6bcbf{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4ed6bcbf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4ed6bcbf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb563004{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb563004 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eb563004{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d1acc551{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d1acc551 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d1acc551{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d6b19b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4ed6bcbf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4ed6bcbf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4ed6bcbf{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eb563004{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eb563004 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eb563004{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;} .uagb-block-f286b3bf.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d1acc551{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d1acc551 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d1acc551{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1d6b19b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1d6b19b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-1d6b19b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}\";s:2:\"js\";s:2460:\"document.addEventListener(\"DOMContentLoaded\", function(){ var ssLinksParent = document.querySelector( '.uagb-block-13fa4fdc' );\nssLinksParent?.addEventListener( 'keyup', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link && e.keyCode === 13 ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nssLinksParent?.addEventListener( 'click', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nfunction handleSocialLinkClick( link ) {\nvar social_url = link.dataset.href;\nvar target = \"\";\nif ( social_url == \"mailto:?body=\" ) {\n\ttarget = \"_self\";\n}\nvar request_url = \"\";\nif ( social_url.indexOf(\"\/pin\/create\/link\/?url=\") !== -1 ) {\n\trequest_url = social_url + encodeURIComponent( window.location.href ) + \"&media=\" + '';\n} else {\n\trequest_url = social_url + encodeURIComponent( window.location.href );\n}\nwindow.open( request_url, target );\n}\n\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-d54b4f1a' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-4d869d83' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\t\t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-f286b3bf' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\t });\";s:18:\"current_block_list\";a:18:{i:0;s:14:\"uagb\/container\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:13:\"uagb\/info-box\";i:7;s:10:\"uagb\/image\";i:8;s:16:\"uagb\/star-rating\";i:10;s:9:\"srfm\/form\";i:11;s:17:\"uagb\/social-share\";i:12;s:23:\"uagb\/social-share-child\";i:13;s:15:\"uagb\/google-map\";i:14;s:11:\"core\/search\";i:15;s:10:\"core\/group\";i:16;s:12:\"core\/heading\";i:17;s:17:\"core\/latest-posts\";i:18;s:20:\"core\/latest-comments\";i:19;s:13:\"core\/archives\";i:20;s:15:\"core\/categories\";i:24;s:14:\"core\/paragraph\";i:27;s:9:\"uagb\/icon\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1777463479\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"code.magna","author_link":"https:\/\/instaframer.com\/dinaspu\/author\/code-magna\/"},"uagb_comment_info":0,"uagb_excerpt":"Kontak Kami Siap Membantu LOKASI KAMI Temukan Kami di Google","meta_box":[],"_links":{"self":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":38,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":1199,"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/pages\/14\/revisions\/1199"}],"wp:attachment":[{"href":"https:\/\/instaframer.com\/dinaspu\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}